{"id":1128,"date":"2023-11-07T10:33:22","date_gmt":"2023-11-07T09:33:22","guid":{"rendered":"https:\/\/wow.cloth.be\/product\/quadro-hocker-weiss\/"},"modified":"2024-03-12T15:15:11","modified_gmt":"2024-03-12T14:15:11","slug":"quadro-hocker-weiss","status":"publish","type":"product","link":"https:\/\/woweventdesign.com\/de\/produit\/quadro-hocker-weiss\/","title":{"rendered":"Quadro Hocker wei\u00df"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2374,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[191,196],"class_list":{"0":"post-1128","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-mobiliar-de","7":"product_cat-hocker-de","8":"pa_beschreibung-weisses-leder-de","9":"ambiance-boho","10":"ambiance-landhausstil","11":"ambiance-lovely-spring-de","12":"ambiance-mediterran","14":"first","15":"instock","16":"product-type-simple"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/woweventdesign.com\/de\/wp-json\/wp\/v2\/product\/1128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/woweventdesign.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/woweventdesign.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/woweventdesign.com\/de\/wp-json\/wp\/v2\/media\/2374"}],"wp:attachment":[{"href":"https:\/\/woweventdesign.com\/de\/wp-json\/wp\/v2\/media?parent=1128"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/woweventdesign.com\/de\/wp-json\/wp\/v2\/product_brand?post=1128"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/woweventdesign.com\/de\/wp-json\/wp\/v2\/product_cat?post=1128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}